{"id":1022,"date":"2017-01-15T12:14:47","date_gmt":"2017-01-15T11:14:47","guid":{"rendered":"http:\/\/www.drachenwerk.at\/aotearoa\/?p=1022"},"modified":"2017-01-15T12:18:40","modified_gmt":"2017-01-15T11:18:40","slug":"ein-paar-reisetipps-zum-abschluss","status":"publish","type":"post","link":"http:\/\/www.babsyundarno.com\/aotearoa\/ein-paar-reisetipps-zum-abschluss\/","title":{"rendered":"Ein paar Reisetipps zum Abschlu\u00df"},"content":{"rendered":"<p>Was haben wir dazugelernt? Was w\u00fcrden wir beim n\u00e4chsten Mal anders machen? Worauf sollte man achten?<\/p>\n<p><strong>Unterkunft finden und buchen<\/strong><br \/>\nAufgrund des Reisebooms nach Neuseeland sind fast alle Hotels, Motels, etc ausgebucht. Wie bei unserem letzten Trip am Nachmittag nach einer Bleibe f\u00fcr die Nacht zu suchen ist zwecklos. Per Internet mindestens eine Woche vorausplanen ist n\u00f6tig. Die Preise haben europ\u00e4ischen Niveau.<\/p>\n<p><strong>Attraktionen<\/strong><br \/>\nMit dem Hubschrauber auf den Gletscher, Wale beobachten etc sind aufgrund der vielen Touristen wi das Suchen nach Unterk\u00fcnften. Vorbuchen ist notwendig. Man kann Neuseeland jedoch auch ganz ohne solche Dinge genie\u00dfen.<\/p>\n<p><strong>Handy und mobiles Internet<\/strong><br \/>\nEs gibt von den Mobilanbietern Pre-paid Karten, die in europ\u00e4ischen Handys ohne Problem funktionieren. Um die \u20ac 20,- f\u00fcr 1 Gb Daten und unlimitiertes Telephonieren in Neuseeland sind ok. F\u00fcr welchen Anbieter man sich entscheidet, gibt die Route vor. Wenn man nur in St\u00e4dten und Ballungszentren unterwegs ist, kommt man mit 2Degrees sehr gut durch. Der Anbieter hat Schw\u00e4chen in l\u00e4ndlichen Gebieten. Will man abseits der Wege reisen, so ist Spark die erste Wahl, die haben das st\u00e4rkste Netz, da\u00df auch in entlegenen Gegenden verf\u00fcgbar ist. Trotzdem darf man hier keine europ\u00e4ische Abdeckung erwarten, es gibt Regionen, da geht einfach nichts.<\/p>\n<p><strong>Ruhe und Entspannung<\/strong><br \/>\nWenn man danach sucht, dann darf man die \u00fcblichen Attraktionen nicht besuchen, denn diese sind mittlerweile \u00fcberlaufen. Aber es gibt noch genug Pl\u00e4tze, die bisher von den Massen verschont sind.<\/p>\n<p><strong>Reiserichtung<\/strong><br \/>\nAlle 5 Reisef\u00fchrer, die wir haben (alle wichtigen) fahren die S\u00fcdinsel gegen den Uhrzeigersin ab (wer da wohl von wem abgeschrieben hat?). Und so fahren auch die meisten Touristen. Wir fahren immer gegen die Richtung, was eine merkliche Erleichterung im Verkehr bedeutet.<\/p>\n<p><strong>Linksverkehr<\/strong><br \/>\nKeine Angst, man gew\u00f6hnt sich schnell daran. Vor allem im l\u00e4ndichen Bereich einfach, kann es in den wenigen Gro\u00dfst\u00e4dten zu Beginn ein wenig mehr Konzentration erfordern.<\/p>\n<p><strong>Mietautos<\/strong><br \/>\nDie Preise f\u00fcr Mietautos sind hier um einiges geringer, als in Europa. 6 Wochen Franz f\u00fcr etwas \u00fcber \u20ac 1.000,-. Zu beachten ist, das Benzin hier um 50% teurer ist, als Diesel und viele Leihautos Benziner sind. Die Treibstoffpreise sind um etwa 20% h\u00f6her als in Europa.<\/p>\n<p><strong>Lebenserhaltungkosten<\/strong><br \/>\nNeuseeland ist preisgleich bis etwas teurer als Europa. Vor allem bei Lebensmitteln gibt es zum Teil Preise, bei denen man fast ohnm\u00e4chtig wird. Wurst, Fleisch und Milch kosten ein Vielfaches von den uns bekannten Preisen. Ein 250 g Joghurt f\u00fcr rund \u20ac 5,- ist normal, Milch f\u00fcr \u00fcber \u20ac 2,- pro Liter ist g\u00fcnstig, 5 kleine Bratw\u00fcrste f\u00fcr \u20ac 6,- sind Diskountware und Obst und Gem\u00fcse sind nur f\u00fcr Besserverdiener.<\/p>\n<p><strong>K\u00fcchen in Unterk\u00fcnften<\/strong><br \/>\nWenn in der Beschreibung der Unterkunft steht mit K\u00fcche, dann sollte man mit seinenn Erwartungen vorsichtig sein. Ein Teekocher, eine Herdplatte zum Anstecken und ein K\u00fchlschrank mit Minieisfach sind schon eine K\u00fcche. Ein Backrohr findet man sehr selten und in dem meisten K\u00fcchen ist mittlerweile das Kochen mit intensiven Gew\u00fcrzen und Knoblauch, sowie mit \u00d6l verboten, das viele Vermieter schlechte Erfahrungen mit asiatischen Reisenden hatten, bzw mit den verbleibenden Ger\u00fcchen.<\/p>\n<p><strong>Alkohol und Rauchen<\/strong><br \/>\nEs gibt Regionen, in den es in Superm\u00e4rkten keinen Alkohol gibt, da hei\u00dft es in den Liquor Store zu gehen. Es gibt auch Bereiche, vor allem in gr\u00f6\u00dferen Orten, in denen man \u00f6ffentlich keinen Alkohol konsumieren darf. Nicht jedes Lokal ist <em>licensed<\/em> Alkohol auszuschenken.<br \/>\nZigaretten sind seit 3 Jahren extrem teuer, \u20ac 20,- pro Packung. Der Zoll l\u00e4\u00dft maximal 50 Zigaretten pro Person ins Land. Und der Preis steigt mit jedem 1. J\u00e4nner um weitere 10%. Ab 2020 ist Tabak dann verboten.<\/p>\n<p><strong>Gep\u00e4ck<\/strong><br \/>\nJe weniger, desto besser. In fast allen Unterk\u00fcnften kann man f\u00fcr kleines Geld W\u00e4sche wachen und Trockner sind hier Standard. 1 Paar stabile Schuhe f\u00fcrs Wandern und Crocs oder Flipflops reichen als Schuhwerk aus. Formelle Kleidung gibt es hier nicht, mit kurzer Hose und Sandalen in ein Lokal zu gehen ist normal. Wer sie noch nicht hat, sollte sich Merinosocken besorgen, perfekt zum Reisen &#8211; warm und nicht hei\u00df, man schwitzt nicht und sie fangen nicht an zu stinken. \ud83d\ude09<\/p>\n<p><strong>Relaxt sein<\/strong><br \/>\nDie Kiwis haben keinen Stress, in keiner Lebenslage. Das mu\u00df man im Hinterkopf haben, wenn es wieder einmal l\u00e4nger dauert bis die Bedienung kommt, die Kassiererin im Supermarkt etwas nachschaut oder um 10 nach das gesch\u00e4ft noch nicht ge\u00f6ffnet hat etc.\u00a0 Das ist die St\u00e4rke der Kiwis. Mir hat ein Einheimischer gesagt: <em>Wir leben auf einer pazifischen Insel. <\/em>\ud83d\ude09<\/p>\n<p><strong>Einkaufen<\/strong><br \/>\nHier gibt es zwei Welten, die gro\u00dfen Ketten (lebensmittel, Baumarkt, &#8230;), die 7 Tage die Woche bis zu 16 Stunden ge\u00f6ffnet haben und die kleinen Shops, die um 09:00 beginnen und um 17:00 zusperren. Man darf sich von Schildern mit der Aussage <em>till late<\/em> nicht t\u00e4uschen lassen, <em>till late<\/em> hei\u00dft <em>bis um F\u00fcnfe<\/em> und nicht <em>lange offen<\/em>.<\/p>\n<p>Wer noch mehr Infos braucht, einfach bei uns nachfragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was haben wir dazugelernt? Was w\u00fcrden wir beim n\u00e4chsten Mal anders machen? Worauf sollte man achten? Unterkunft finden und buchen[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/posts\/1022"}],"collection":[{"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/comments?post=1022"}],"version-history":[{"count":9,"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/posts\/1022\/revisions"}],"predecessor-version":[{"id":1033,"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/posts\/1022\/revisions\/1033"}],"wp:attachment":[{"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/media?parent=1022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/categories?post=1022"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.babsyundarno.com\/aotearoa\/wp-json\/wp\/v2\/tags?post=1022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}